{"id":69,"count":4,"description":"","link":"https:\/\/www.detailingaddict.com\/nl\/c\/polijsten\/","name":"Polijsten","slug":"polijsten","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Producten voor polijsten kopen? Shop bij Detailing Addict!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.detailingaddict.com\/nl\/c\/polijsten\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Producten voor polijsten kopen? Shop bij Detailing Addict!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.detailingaddict.com\/nl\/c\/polijsten\/\" \/>\n<meta property=\"og:site_name\" content=\"Detailing Addict\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/c\\\/polijsten\\\/\",\"url\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/c\\\/polijsten\\\/\",\"name\":\"Producten voor polijsten kopen? Shop bij Detailing Addict!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/c\\\/polijsten\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/c\\\/polijsten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polijsten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/\",\"name\":\"Detailing Addict\",\"description\":\"Detailing Addict helpt jou om op een makkelijke manier te (starten met) detailen en volop van je auto te genieten!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/#organization\",\"name\":\"Detailing Addict\",\"url\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/02\\\/cropped-Detailling-Addict-B.V.-Logo-1000x1000-1-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/02\\\/cropped-Detailling-Addict-B.V.-Logo-1000x1000-1-scaled-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Detailing Addict\"},\"image\":{\"@id\":\"https:\\\/\\\/www.detailingaddict.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/detailingaddictcom\",\"https:\\\/\\\/www.youtube.com\\\/@detailingaddict_com\",\"https:\\\/\\\/www.instagram.com\\\/detailingaddict_com\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@detailingaddict_com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Producten voor polijsten kopen? Shop bij Detailing Addict!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.detailingaddict.com\/nl\/c\/polijsten\/","og_locale":"nl_NL","og_type":"article","og_title":"Producten voor polijsten kopen? Shop bij Detailing Addict!","og_url":"https:\/\/www.detailingaddict.com\/nl\/c\/polijsten\/","og_site_name":"Detailing Addict","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.detailingaddict.com\/nl\/c\/polijsten\/","url":"https:\/\/www.detailingaddict.com\/nl\/c\/polijsten\/","name":"Producten voor polijsten kopen? Shop bij Detailing Addict!","isPartOf":{"@id":"https:\/\/www.detailingaddict.com\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/www.detailingaddict.com\/nl\/c\/polijsten\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.detailingaddict.com\/nl\/c\/polijsten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.detailingaddict.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Polijsten"}]},{"@type":"WebSite","@id":"https:\/\/www.detailingaddict.com\/nl\/#website","url":"https:\/\/www.detailingaddict.com\/nl\/","name":"Detailing Addict","description":"Detailing Addict helpt jou om op een makkelijke manier te (starten met) detailen en volop van je auto te genieten!","publisher":{"@id":"https:\/\/www.detailingaddict.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.detailingaddict.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.detailingaddict.com\/nl\/#organization","name":"Detailing Addict","url":"https:\/\/www.detailingaddict.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.detailingaddict.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.detailingaddict.com\/nl\/wp-content\/uploads\/sites\/3\/2023\/02\/cropped-Detailling-Addict-B.V.-Logo-1000x1000-1-scaled-1.jpg","contentUrl":"https:\/\/www.detailingaddict.com\/nl\/wp-content\/uploads\/sites\/3\/2023\/02\/cropped-Detailling-Addict-B.V.-Logo-1000x1000-1-scaled-1.jpg","width":512,"height":512,"caption":"Detailing Addict"},"image":{"@id":"https:\/\/www.detailingaddict.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/detailingaddictcom","https:\/\/www.youtube.com\/@detailingaddict_com","https:\/\/www.instagram.com\/detailingaddict_com\/","https:\/\/www.tiktok.com\/@detailingaddict_com"]}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.detailingaddict.com\/nl\/wp-json\/wp\/v2\/product_cat\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.detailingaddict.com\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.detailingaddict.com\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.detailingaddict.com\/nl\/wp-json\/wp\/v2\/product?product_cat=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}